{"id":106750,"date":"2022-10-05T03:54:34","date_gmt":"2022-10-05T01:54:34","guid":{"rendered":"https:\/\/pre.efe.com\/?p=106750"},"modified":"2022-10-05T04:07:16","modified_gmt":"2022-10-05T02:07:16","slug":"no-coracao-da-copa-do-mundo-do-qatar-2022","status":"publish","type":"post","link":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/","title":{"rendered":"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022"},"content":{"rendered":"\n<p>Javier Picazo Feli\u00fa.<\/p>\n\n\n\n<p>Doha (<a href=\"https:\/\/pre.efe.com\/pt-br\/\">EFE<\/a>).- Doha, a maior entre as cidades-sede da Copa do Mundo Qatar 2022, \u00e9 uma capital moderna com um perfil futurista em que arranha-c\u00e9us, edif\u00edcios de projetos arrojados, ruas e cal\u00e7ad\u00f5es completamente remodelados para o evento chamam muito a aten\u00e7\u00e3o, assim como a extrema perfei\u00e7\u00e3o em detalhes e limpeza, e esses avan\u00e7os contrastam com a tradi\u00e7\u00e3o e a hist\u00f3ria de um povo de tribos migrat\u00f3rias cujo cora\u00e7\u00e3o est\u00e1 no mercado popular Souq Waqif.<\/p>\n\n\n\n<p>Mas, como tudo no Qatar, ele \u00e9 tamb\u00e9m uma cria\u00e7\u00e3o recente. Concebido no final do s\u00e9culo XIX como um centro de com\u00e9rcio e interc\u00e2mbio de gado entre bedu\u00ednos e comerciantes, o Souq Waqif (que pode significar &#8220;mercado ambulante&#8221;) que podemos ver agora foi conclu\u00eddo em 2008 e abrange o antigo bairro de Al-Yassra, as \u00e1reas de maior atividade pesqueira, v\u00e1rios cemit\u00e9rios onde hoje existe um enorme estacionamento subterr\u00e2neo e uma parte aterrada onde antes era mar.<\/p>\n\n\n\n<p>A primeira coisa que chama a aten\u00e7\u00e3o \u00e9 a arquitetura peculiar. O mercado foi constru\u00eddo de maneira tradicional para preservar o encanto dos tempos passados e, acima de tudo, para enfrentar as alt\u00edssimas temperaturas do ver\u00e3o: a estrutura conta com barro, e o telhado, com bambu.<\/p>\n\n\n\n<p>O mercado \u00e9 a principal atra\u00e7\u00e3o para os turistas que v\u00eam a Doha para a Copa do Mundo Qatar 2022. Por ter sido constru\u00eddo t\u00e3o recentemente, parece um cen\u00e1rio de cinema ou uma atra\u00e7\u00e3o de parques tem\u00e1ticos, mas trata-se apenas de uma primeira impress\u00e3o.<\/p>\n\n\n\n<p>Tudo sobre este lugar \u00e9 perfeito. Encantador. Lanternas de luz t\u00eanue nas fachadas, pequenas pra\u00e7as cheias de vida ou sua rede labir\u00edntica de corredores, com milhares de lojas vendendo tudo, de camisas de futebol, tecidos e especiarias at\u00e9 as cobi\u00e7adas e famosas p\u00e9rolas, j\u00f3ias, ouro ou animais de todos os tipos. Em Souq Waqif \u00e9 imposs\u00edvel n\u00e3o sentir que voc\u00ea est\u00e1 em outro mundo.<\/p>\n\n\n\n<p>As pessoas que fazem parte do lugar, a hist\u00f3ria de cada pequena loja, os aromas, a \u00e1rea de venda de falc\u00f5es e a variada gastronomia, que inclui tudo, desde a melhor comida de rua da regi\u00e3o at\u00e9 os melhores restaurantes, fazem desse local uma parada obrigat\u00f3ria.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;\u00c9 um mercado real h\u00e1 mais de 100 anos. Ainda \u00e9 utilizado pelos qatarianos. Claro, \u00e9 tamb\u00e9m uma grande atra\u00e7\u00e3o tur\u00edstica. Definitivamente, se eu viesse ao Qatar, eu iria a um dos restaurantes de l\u00e1. Voc\u00ea encontrar\u00e1 todo tipo de cozinha, do Ir\u00e3 ou de qualquer um dos pa\u00edses vizinhos&#8221;, disse Berthold Trenkel, diretor de opera\u00e7\u00f5es de Turismo do Qatar.<\/p><\/blockquote>\n\n\n\n<p>Trenkel, que \u00e9 apaixonado por fotografia, recomenda que se fa\u00e7a um tour pelo local &#8220;se deixando impressionar&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Acho que esse \u00e9 o principal objetivo quando voc\u00ea visita o Qatar. \u00c9 um pa\u00eds muito moderno, mas profundamente enraizado em sua cultura e heran\u00e7a. \u00c9 preciso estar aberto a novas coisas, experimentar novos alimentos, novas experi\u00eancias e, \u00e9 claro, curtir a Copa do Mundo&#8221;, afirmou.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Souq, o lugar perfeito no Qatar para despertar os 5 sentidos:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-2.jpg\" alt=\"\" class=\"wp-image-106778\" width=\"979\" height=\"652\" srcset=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-2.jpg 900w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-2-300x200.jpg 300w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-2-768x511.jpg 768w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-2-430x286.jpg 430w\" sizes=\"(max-width: 979px) 100vw, 979px\" \/><figcaption><em>O grande bazar do souq, em Doha, no Qatar. <strong>EFE\/Alberto Est\u00e9vez<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">1.- Vis\u00e3o: dentro do labirinto<\/h3>\n\n\n\n<p>A rede de vielas cobertas do grande bazar do souq \u00e9 labir\u00edntica. \u00c9 muito f\u00e1cil de se perder, e as \u00fanicas refer\u00eancias s\u00e3o certos produtos e \u00e1reas especializadas espec\u00edficas: tapetes, tecidos, especiarias, ouro, utens\u00edlios de cozinha e milhares de tesouros e antiguidades a serem encontrados que recompensam os mais curiosos compradores.<\/p>\n\n\n\n<p>Nas manh\u00e3s dos dias \u00fateis, durante as horas mais quentes do dia, o souq muda completamente. A maioria das lojas est\u00e1 fechada, e o sil\u00eancio impera.<\/p>\n\n\n\n<p>\u00c9 uma paz que vale a pena descobrir passeando por estreitos recantos admirando as tradicionais portas de madeira de cada loja. Saborear a lenta abertura e o in\u00edcio da atividade fren\u00e9tica que antecipa o p\u00f4r-do-sol, quando o souq se enche com a luz das lanternas, a cor, os gritos caracter\u00edsticos de feiras livres e os cheiros do Oriente. \u00c9 um movimento incessante de pessoas que preenche com vida cada metro das vielas de paralelep\u00edpedos e recantos buc\u00f3licos.<\/p>\n\n\n\n<p>Entre os segredos do souq est\u00e3o os Majlis (&#8220;lugares para sentar&#8221;), pontos de encontro cheios de almofadas, tapetes e mesas baixas, geralmente para homens, onde as t\u00e1buas de gam\u00e3o desempenham um papel fundamental no entretenimento da sociedade tradicional do Qatar.<\/p>\n\n\n\n<p>Nestes lugares, inscritos na Lista Representativa do Patrim\u00f4nio Cultural Imaterial da Humanidade da UNESCO, as pessoas discutem assuntos de interesse comum degustando uma bebida quente &#8211; ch\u00e1 ou caf\u00e9 &#8211; e recebem convidados. Visit\u00e1-los \u00e9 uma experi\u00eancia muito interessante que permite vivenciar a cultura do pa\u00eds.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 importante destacar a majestosa presen\u00e7a da Fanar, uma mesquita com uma caprichosa forma curvada que lembra um farol em espiral. \u00c9 um dos marcos mais famosos da capital, vis\u00edvel do cal\u00e7ad\u00e3o de Corniche e dos museus de Arte Isl\u00e2mica e Nacional do Qatar. Elegante e solene, \u00e9 uma mesquita em funcionamento. Ela recebe n\u00e3o apenas eventos religiosos, mas tamb\u00e9m \u00e9 um centro cultural no qual se pode tomar um caf\u00e9 e mergulhar na vida do pa\u00eds.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2.- Olfato: os comerciantes de especiarias e perfumes<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-ESPECIARIAS.jpg\" alt=\"\" class=\"wp-image-106799\" width=\"978\" height=\"652\" srcset=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-ESPECIARIAS.jpg 900w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-ESPECIARIAS-300x200.jpg 300w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-ESPECIARIAS-768x512.jpg 768w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-ESPECIARIAS-430x286.jpg 430w\" sizes=\"(max-width: 978px) 100vw, 978px\" \/><figcaption><em>Uma loja de especiarias do Souq Waqif. <strong>EFE\/Alberto Est\u00e9vez<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>Nas vielas do souq, o olfato guia por uma das \u00e1reas mais coloridas e frequentadas: a das especiarias. Os sacos de juta amontoados nas portas das lojas d\u00e3o as boas vindas a um mundo para os sentidos proveniente de muito al\u00e9m das fronteiras do Qatar. Em particular, de todos os cantos da pen\u00ednsula ar\u00e1bica, da \u00cdndia e do Ir\u00e3. A\u00e7afr\u00e3o, flores secas para infus\u00f5es, t\u00e2maras, mel, curry e muito mais.<\/p>\n\n\n\n<p>Os comerciantes escondem com desconfian\u00e7a e orgulho a receita que torna seu tempero \u00fanico, o que os distingue e lhes d\u00e1 reputa\u00e7\u00e3o. Porque, no Qatar, cada fam\u00edlia faz sua pr\u00f3pria mistura, sua pr\u00f3pria f\u00f3rmula secreta. Esta especiaria local \u00fanica, transmitida de gera\u00e7\u00e3o em gera\u00e7\u00e3o, \u00e9 chamada Bezar.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;S\u00e3o muitas especiarias em uma. Normalmente a mistura cont\u00e9m cominho, c\u00farcuma, canela, pimenta preta, coentro, cardamomo&#8230;. Cada um tem sua pr\u00f3pria mistura. \u00c9 algo \u00fanico que usamos em muitos pratos como machboos (prato nacional do Qatar cozido com arroz e carne de frango, bovina ou at\u00e9 de camelo). Voc\u00ea compra e adiciona a qualquer prato. \u00c9 incr\u00edvel&#8221;, disse o chef Noor Al Mazrooi, uma das mais importantes refer\u00eancias gastron\u00f4micas da nova cozinha qatariana.<\/p><\/blockquote>\n\n\n\n<p>Tamb\u00e9m \u00e9 poss\u00edvel criar suas pr\u00f3prias especiarias nas lojas especializadas. Se voc\u00ea gosta de ch\u00e1 iraniano com cardamomo e cravo, por exemplo, basta encomendar e buscar. Ou um curry em p\u00f3 indiano misturado com canela ou pimenta-caiena. N\u00e3o h\u00e1 problema, as possibilidades s\u00e3o quase infinitas. Deixar que os especialistas em aromas e sabores o aconselhem \u00e9 uma experi\u00eancia muito enriquecedora.<\/p>\n\n\n\n<p>O olfato tamb\u00e9m desempenha um papel de destaque nos milhares de pequenas lojas que vendem perfumes e cremes para a pele. Muitos s\u00e3o produzidos sob encomenda, como alm\u00edscar, kohl e \u00f3leo de argan. S\u00e3o combina\u00e7\u00f5es pessoais dependendo da pele, feitas com cuidado e personalizadas de acordo com as receitas tradicionais \u00e1rabes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3.- Paladar: tabernas e comida de rua<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"599\" height=\"900\" src=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-GASTRONOMIA.jpg\" alt=\"\" class=\"wp-image-106787\" srcset=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-GASTRONOMIA.jpg 599w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-GASTRONOMIA-200x300.jpg 200w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-GASTRONOMIA-190x286.jpg 190w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><figcaption><em>Pratos servidos por um restaurante do Souq Waqif. <strong>EFE\/Alberto Est\u00e9vez<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>Em um souq voc\u00ea encontra de tudo, e quando se trata de comer, n\u00e3o \u00e9 diferente. Comida de rua, lojas de doces, restaurantes, cozinha qatariana, libanesa, iemenita, turca e iraniana. Nada escapa \u00e0 oferta do Souq Waqif.<\/p>\n\n\n\n<p>Uma sugest\u00e3o \u00e9 come\u00e7ar com samboosa, pequenos past\u00e9is crocantes recheados com vegetais, carne ou queijo, continuar com um falafel de gr\u00e3o de bico, apreciar espetinhos de kafta grelhados com hommus ou salada e experimentar machboos. De sobremesa, caem muito bem bolinhos de luqaimat de mel (considerada a sobremesa mais antiga do mundo), kunafas de queijo derretido ou regag (panquecas de queijo fundido, frutas ou chocolate. Sempre acompanhado de karak, o ch\u00e1 doce do Qatar com leite.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;A cozinha qatariana \u00e9 uma experi\u00eancia maravilhosa. Tem uma infinidade de sabores, muitas especiarias. Cada prato tem uma receita \u00fanica. \u00c9 por isso que, quando voc\u00ea os experimenta, eles nunca s\u00e3o os mesmos. Tem que provar tudo. Os torcedores que vierem \u00e0 Copa do Mundo t\u00eam que ir a lugares que t\u00eam comida do Catar e provar esta deliciosa experi\u00eancia&#8221;, afirmou o chef Noor.<\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">4.- Tato: p\u00e9rolas e ouro<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-JOALHERIA.jpg\" alt=\"\" class=\"wp-image-106810\" width=\"978\" height=\"652\" srcset=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-JOALHERIA.jpg 900w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-JOALHERIA-300x200.jpg 300w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-JOALHERIA-768x512.jpg 768w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-JOALHERIA-430x286.jpg 430w\" sizes=\"(max-width: 978px) 100vw, 978px\" \/><figcaption><em>Uma joalheria<\/em> no<em> Souq Waqif. <strong>EFE\/Alberto Est\u00e9vez<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>O passado do Qatar est\u00e1 ligado a p\u00e9rolas, uma de suas principais fontes de receita e o que lhe trouxe fama internacional. No souq \u00e9 poss\u00edvel encontrar lojas onde se pode aprender sobre suas variedades, geralmente rosa, branco e cinza, e descobrir as particularidades de um com\u00e9rcio que agora est\u00e1 quase extinto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;A pesca de p\u00e9rolas \u00e9 coisa do passado. Foi o modelo econ\u00f4mico h\u00e1 100 cem anos. Naquela \u00e9poca, a popula\u00e7\u00e3o do Oriente M\u00e9dio era muito esparsa. Havia bedu\u00ednos que vagueavam pela regi\u00e3o, mas tamb\u00e9m havia pessoas que tinham desenvolvido a principal maneira ou meio de ganhar dinheiro, que era ir pescar p\u00e9rolas. Isso foi antes da inven\u00e7\u00e3o das p\u00e9rolas sint\u00e9ticas que tiveram um enorme impacto econ\u00f4mico nesta regi\u00e3o e praticamente eliminaram a pesca de p\u00e9rolas. Voc\u00ea ainda pode encontrar p\u00e9rolas originais do Qatar, mas elas s\u00e3o muito caras&#8221;, disse Berthold Trenkel.<\/p><\/blockquote>\n\n\n\n<p>Perto do centro nervoso do souq est\u00e1 outro lugar essencial para aprender o peso e a forma de outro produto de luxo, o ouro. No Gold Souq podemos encontrar uma enorme variedade de joias tradicionais e de design moderno. Uma das principais caracter\u00edsticas deste mercado \u00e9 que as pe\u00e7as t\u00eam que ser pesadas na frente do comprador antes de serem vendidas, e todas foram previamente analisadas para garantir sua qualidade. Com um or\u00e7amento apertado, \u00e9 poss\u00edvel comprar colares ou pulseiras com o nome gravado em \u00e1rabe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5.- Audi\u00e7\u00e3o: falc\u00f5es e variedades animais<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-FALCAO.jpg\" alt=\"\" class=\"wp-image-106804\" width=\"980\" height=\"652\" srcset=\"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-FALCAO.jpg 900w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-FALCAO-300x200.jpg 300w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-FALCAO-768x511.jpg 768w, https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR-FALCAO-430x286.jpg 430w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><figcaption><em>Um homem com seu falc\u00e3o em um hospital especializado no Souq Waqif. <strong>EFE\/Alberto Est\u00e9vez<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>O animal mais representativo do Qatar \u00e9 o falc\u00e3o. Faz parte da cultura do pa\u00eds n\u00e3o apenas para a falcoaria, que remonta ao tempo das tribos bedu\u00ednas, mas tamb\u00e9m como um emblema e uma fonte de orgulho familiar. Qualquer visitante compreender\u00e1 isso rapidamente. Um enorme falc\u00e3o dourado o espera no aeroporto, e nas \u00e1reas tur\u00edsticas geralmente h\u00e1 uma loja onde \u00e9 poss\u00edvel tirar uma foto com um desses preciosos animais no bra\u00e7o.<\/p>\n\n\n\n<p>Em Souq Waqif, podemos encontrar uma \u00e1rea exclusiva para falc\u00f5es.&nbsp; N\u00e3o s\u00f3 existem lojas vendendo todos os tipos de falc\u00f5es, desde os famosos falc\u00f5es brancos at\u00e9 os falc\u00f5es sagrados ou peregrinos, todos ca\u00e7adores de renome, mas tamb\u00e9m sistemas GPS para n\u00e3o perd\u00ea-los, capuzes, gaiolas de transporte e todos os tipos de acess\u00f3rios, cada um mais improv\u00e1vel que o outro. L\u00e1 tamb\u00e9m fica o hospital dos falc\u00f5es. Um lugar de visita obrigat\u00f3ria, nem que seja para ver uma sala de espera com os animais e seus donos esperando atendimento depois de terem sofrido um contratempo ou para um check-up de rotina.&nbsp;<\/p>\n\n\n\n<p>Voltando ao souq, o chilrear das aves antecipa a chegada do mercado de animais de estima\u00e7\u00e3o &#8211; uma pra\u00e7a e v\u00e1rias ruas com todos os tipos de animais. Coelhos, tartarugas, papagaios, patos e uma infinidade de variedades de p\u00e1ssaros (em sua maioria enjaulados) e todos os acess\u00f3rios necess\u00e1rios para cuidar deles. \u00c9 certamente uma das partes mais ex\u00f3ticas do bazar do Qatar.\u00a0O souq \u00e9, sem d\u00favida, uma parada essencial para todos aqueles que v\u00eam \u00e0 Copa do Mundo: visite-o e deixe-se levar pela tradi\u00e7\u00e3o e pelos sentidos de um lugar m\u00e1gico para se lembrar. <a href=\"https:\/\/efs.efeservicios.com\/\">EFE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Javier Picazo Feli\u00fa. Doha (EFE).- Doha, a maior entre as cidades-sede da Copa do Mundo Qatar 2022, \u00e9 uma capital moderna com um perfil futurista em que arranha-c\u00e9us, edif\u00edcios de projetos arrojados, ruas e cal\u00e7ad\u00f5es completamente remodelados para o evento chamam muito a aten\u00e7\u00e3o, assim como a extrema perfei\u00e7\u00e3o em detalhes e limpeza, e esses &#8230; <a title=\"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022\" class=\"read-more\" href=\"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/\" aria-label=\"Read more about No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022\">Leia mais<\/a><\/p>\n","protected":false},"author":198164106,"featured_media":106775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[121968,122144],"tags":[],"class_list":["post-106750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-outras-noticias","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022<\/title>\n<meta name=\"description\" content=\"Doha, a maior das cidades-sede do Mundial Qatar 2022, \u00e9 moderna e futurista, o que contrasta com a hist\u00f3ria de um povo de tribos migrat\u00f3rias.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022 - EFE\" \/>\n<meta property=\"og:description\" content=\"Doha, a maior das cidades-sede do Mundial Qatar 2022, \u00e9 moderna e futurista, o que contrasta com a hist\u00f3ria de um povo de tribos migrat\u00f3rias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"EFE Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AgenciaEFEnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T01:54:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T02:07:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/efe.com\/\/srv\/htdocs\/wp-content\/uploads\/2022\/10\/QATAR.jpg?fit=900%2C600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anachain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@efenoticias\" \/>\n<meta name=\"twitter:site\" content=\"@efenoticias\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/\"},\"author\":{\"name\":\"anachain\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b19f23f210db552768f68a4b552b004f\"},\"headline\":\"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022\",\"datePublished\":\"2022-10-05T01:54:34+00:00\",\"dateModified\":\"2022-10-05T02:07:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/\"},\"wordCount\":2026,\"publisher\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/QATAR.jpg\",\"articleSection\":[\"Esportes\",\"Outras not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/#organization\"}},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/\",\"name\":\"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/QATAR.jpg\",\"datePublished\":\"2022-10-05T01:54:34+00:00\",\"dateModified\":\"2022-10-05T02:07:16+00:00\",\"description\":\"Doha, a maior das cidades-sede do Mundial Qatar 2022, \u00e9 moderna e futurista, o que contrasta com a hist\u00f3ria de um povo de tribos migrat\u00f3rias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/QATAR.jpg\",\"contentUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/QATAR.jpg\",\"width\":900,\"height\":600,\"caption\":\"Doha, capital do Qatar, EFE\\\/ Alberto Est\u00e9vez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2022-10-05\\\/no-coracao-da-copa-do-mundo-do-qatar-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\",\"name\":\"EFE Noticias\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\",\"name\":\"Agencia EFE\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-efe-467.png\",\"contentUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-efe-467.png\",\"width\":467,\"height\":467,\"caption\":\"Agencia EFE\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AgenciaEFEnoticias\\\/\",\"https:\\\/\\\/x.com\\\/efenoticias\",\"https:\\\/\\\/www.instagram.com\\\/efe_noticias\\\/\",\"http:\\\/\\\/www.youtube.com\\\/efe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b19f23f210db552768f68a4b552b004f\",\"name\":\"anachain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"caption\":\"anachain\"},\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/autor\\\/anachain\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022","description":"Doha, a maior das cidades-sede do Mundial Qatar 2022, \u00e9 moderna e futurista, o que contrasta com a hist\u00f3ria de um povo de tribos migrat\u00f3rias.","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022 - EFE","og_description":"Doha, a maior das cidades-sede do Mundial Qatar 2022, \u00e9 moderna e futurista, o que contrasta com a hist\u00f3ria de um povo de tribos migrat\u00f3rias.","og_url":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/","og_site_name":"EFE Noticias","article_publisher":"https:\/\/www.facebook.com\/AgenciaEFEnoticias\/","article_published_time":"2022-10-05T01:54:34+00:00","article_modified_time":"2022-10-05T02:07:16+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/i0.wp.com\/efe.com\/\/srv\/htdocs\/wp-content\/uploads\/2022\/10\/QATAR.jpg?fit=900%2C600&ssl=1","type":"image\/jpeg"}],"author":"anachain","twitter_card":"summary_large_image","twitter_creator":"@efenoticias","twitter_site":"@efenoticias","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#article","isPartOf":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/"},"author":{"name":"anachain","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/person\/b19f23f210db552768f68a4b552b004f"},"headline":"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022","datePublished":"2022-10-05T01:54:34+00:00","dateModified":"2022-10-05T02:07:16+00:00","mainEntityOfPage":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/"},"wordCount":2026,"publisher":{"@id":"https:\/\/pre.efe.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR.jpg","articleSection":["Esportes","Outras not\u00edcias"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/pre.efe.com\/#organization"}},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/","url":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/","name":"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022","isPartOf":{"@id":"https:\/\/pre.efe.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#primaryimage"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR.jpg","datePublished":"2022-10-05T01:54:34+00:00","dateModified":"2022-10-05T02:07:16+00:00","description":"Doha, a maior das cidades-sede do Mundial Qatar 2022, \u00e9 moderna e futurista, o que contrasta com a hist\u00f3ria de um povo de tribos migrat\u00f3rias.","breadcrumb":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#primaryimage","url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR.jpg","contentUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR.jpg","width":900,"height":600,"caption":"Doha, capital do Qatar, EFE\/ Alberto Est\u00e9vez"},{"@type":"BreadcrumbList","@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2022-10-05\/no-coracao-da-copa-do-mundo-do-qatar-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pre.efe.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"No cora\u00e7\u00e3o da Copa do Mundo do Qatar 2022"}]},{"@type":"WebSite","@id":"https:\/\/pre.efe.com\/pt-br\/#website","url":"https:\/\/pre.efe.com\/pt-br\/","name":"EFE Noticias","description":"","publisher":{"@id":"https:\/\/pre.efe.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pre.efe.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/pre.efe.com\/pt-br\/#organization","name":"Agencia EFE","url":"https:\/\/pre.efe.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/06\/logo-efe-467.png","contentUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/06\/logo-efe-467.png","width":467,"height":467,"caption":"Agencia EFE"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AgenciaEFEnoticias\/","https:\/\/x.com\/efenoticias","https:\/\/www.instagram.com\/efe_noticias\/","http:\/\/www.youtube.com\/efe"]},{"@type":"Person","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/person\/b19f23f210db552768f68a4b552b004f","name":"anachain","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","caption":"anachain"},"url":"https:\/\/pre.efe.com\/pt-br\/autor\/anachain\/"}]}},"jetpack_featured_media_url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2022\/10\/QATAR.jpg","jetpack_shortlink":"https:\/\/wp.me\/peJvHm-rLM","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/106750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/users\/198164106"}],"replies":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/comments?post=106750"}],"version-history":[{"count":7,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/106750\/revisions"}],"predecessor-version":[{"id":106822,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/106750\/revisions\/106822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/media\/106775"}],"wp:attachment":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/media?parent=106750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/categories?post=106750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/tags?post=106750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}