{"id":650625,"date":"2023-09-15T21:21:00","date_gmt":"2023-09-15T19:21:00","guid":{"rendered":"https:\/\/pre.efe.com\/?p=650625"},"modified":"2023-09-18T19:27:39","modified_gmt":"2023-09-18T17:27:39","slug":"promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso","status":"publish","type":"post","link":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/","title":{"rendered":"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso"},"content":{"rendered":"\n<p>Madri (EFE).- A Promotoria pediu ao juiz que investiga o beijo sem consentimento do ex-presidente da Federa\u00e7\u00e3o Espanhola de Futebol (RFEF), Luis Rubiales, em Jenni Hermoso e a suposta coa\u00e7\u00e3o para impedir que ele se aproxime a menos de 500 metros da jogadora e nem comunicar-se com ela por qualquer meio durante a investiga\u00e7\u00e3o do caso.<\/p>\n\n\n\n<p>Fontes fiscais relataram o pedido, que tamb\u00e9m solicita que Rubiales compare\u00e7a a cada 15 dias perante o juiz, que agora deve decidir se concorda com essas solicita\u00e7\u00f5es.<\/p>\n\n\n\n<p>O ex-presidente da RFEF compareceu durante uma hora e respondeu \u00e0s perguntas do juiz do Tribunal Nacional Francisco de Jorge e de todas as partes, negando os fatos de que \u00e9 acusado, tanto a coa\u00e7\u00e3o como a falta de consentimento no beijo, segundo as fontes citadas.<\/p>\n\n\n\n<p>Por sua vez, a advogada de Jenni Hermoso, Carla Vall, tamb\u00e9m presente no depoimento, solicitou, como a Procuradoria, medidas cautelares para Rubiales, e reiterou que &#8220;foi um beijo n\u00e3o consentido&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cTodos viram as imagens, todo o pa\u00eds viu. E podemos dizer precisamente que gra\u00e7as a isso, gra\u00e7as tamb\u00e9m \u00e0 mudan\u00e7a social, \u00e0 mudan\u00e7a jur\u00eddica, de alguma forma podemos sustentar que houve uma total falta de consentimento por parte do senhor Rubiales\u201d, afirmou em declara\u00e7\u00f5es a jornalistas reunidos perante o Tribunal.<\/p>\n<\/blockquote>\n\n\n\n<p>Vall, que agradeceu a aten\u00e7\u00e3o que o caso est\u00e1 recebendo, indicou que Hermoso est\u00e1 \u201ccomovida\u201d pelo ocorrido, \u201cpelo ato humilhante que sofreu no est\u00e1dio e que manchou um marco esportivo, uma vit\u00f3ria t\u00e3o grande\u201d.<\/p>\n\n\n\n<p>Neste contexto, pediu um tratamento adequado \u201cpara sustentar emocionalmente este processo\u201d.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o a este assunto, a delegada do Governo contra a Viol\u00eancia de G\u00eanero, Victoria Rosell, afirmou que \u00e9 \u201creconfortante\u201d que a Procuradoria solicite medidas cautelares contra Rubiales. \u201cN\u00e3o se aproximar da pessoa ofendida, proibir a comunica\u00e7\u00e3o com ela ou sua fam\u00edlia por qualquer meio. \u00c9 importante pela suposta agress\u00e3o e coa\u00e7\u00e3o\u201d, observou. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madri (EFE).- A Promotoria pediu ao juiz que investiga o beijo sem consentimento do ex-presidente da Federa\u00e7\u00e3o Espanhola de Futebol (RFEF), Luis Rubiales, em Jenni Hermoso e a suposta coa\u00e7\u00e3o para impedir que ele se aproxime a menos de 500 metros da jogadora e nem comunicar-se com ela por qualquer meio durante a investiga\u00e7\u00e3o do &#8230; <a title=\"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso\" class=\"read-more\" href=\"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/\" aria-label=\"Read more about Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso\">Leia mais<\/a><\/p>\n","protected":false},"author":198164106,"featured_media":637785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[121968,122141],"tags":[],"class_list":["post-650625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-portada","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso - EFE<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso - EFE\" \/>\n<meta property=\"og:description\" content=\"Madri (EFE).- A Promotoria pediu ao juiz que investiga o beijo sem consentimento do ex-presidente da Federa\u00e7\u00e3o Espanhola de Futebol (RFEF), Luis Rubiales, em Jenni Hermoso e a suposta coa\u00e7\u00e3o para impedir que ele se aproxime a menos de 500 metros da jogadora e nem comunicar-se com ela por qualquer meio durante a investiga\u00e7\u00e3o do ... Leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/\" \/>\n<meta property=\"og:site_name\" content=\"EFE Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AgenciaEFEnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-15T19:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T17:27:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/efe.com\/\/srv\/htdocs\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg?fit=1920%2C1282&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anachain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@efenoticias\" \/>\n<meta name=\"twitter:site\" content=\"@efenoticias\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/\"},\"author\":{\"name\":\"anachain\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b19f23f210db552768f68a4b552b004f\"},\"headline\":\"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso\",\"datePublished\":\"2023-09-15T19:21:00+00:00\",\"dateModified\":\"2023-09-18T17:27:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/\"},\"wordCount\":346,\"publisher\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg\",\"articleSection\":[\"Esportes\",\"Portada\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/#organization\"}},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/\",\"name\":\"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso - EFE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg\",\"datePublished\":\"2023-09-15T19:21:00+00:00\",\"dateModified\":\"2023-09-18T17:27:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg\",\"contentUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg\",\"width\":1920,\"height\":1282,\"caption\":\"El expresidente de la Federaci\u00f3n Espa\u00f1ola de F\u00fatbol, Luis Rubiales en una foto de archivo. EFE\\\/JJ Guill\u00e9n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/esportes\\\/2023-09-15\\\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\",\"name\":\"EFE Noticias\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\",\"name\":\"Agencia EFE\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-efe-467.png\",\"contentUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-efe-467.png\",\"width\":467,\"height\":467,\"caption\":\"Agencia EFE\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AgenciaEFEnoticias\\\/\",\"https:\\\/\\\/x.com\\\/efenoticias\",\"https:\\\/\\\/www.instagram.com\\\/efe_noticias\\\/\",\"http:\\\/\\\/www.youtube.com\\\/efe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b19f23f210db552768f68a4b552b004f\",\"name\":\"anachain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"caption\":\"anachain\"},\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/autor\\\/anachain\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso - EFE","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso - EFE","og_description":"Madri (EFE).- A Promotoria pediu ao juiz que investiga o beijo sem consentimento do ex-presidente da Federa\u00e7\u00e3o Espanhola de Futebol (RFEF), Luis Rubiales, em Jenni Hermoso e a suposta coa\u00e7\u00e3o para impedir que ele se aproxime a menos de 500 metros da jogadora e nem comunicar-se com ela por qualquer meio durante a investiga\u00e7\u00e3o do ... Leia mais","og_url":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/","og_site_name":"EFE Noticias","article_publisher":"https:\/\/www.facebook.com\/AgenciaEFEnoticias\/","article_published_time":"2023-09-15T19:21:00+00:00","article_modified_time":"2023-09-18T17:27:39+00:00","og_image":[{"width":1920,"height":1282,"url":"https:\/\/i0.wp.com\/efe.com\/\/srv\/htdocs\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg?fit=1920%2C1282&ssl=1","type":"image\/jpeg"}],"author":"anachain","twitter_card":"summary_large_image","twitter_creator":"@efenoticias","twitter_site":"@efenoticias","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#article","isPartOf":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/"},"author":{"name":"anachain","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/person\/b19f23f210db552768f68a4b552b004f"},"headline":"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso","datePublished":"2023-09-15T19:21:00+00:00","dateModified":"2023-09-18T17:27:39+00:00","mainEntityOfPage":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/"},"wordCount":346,"publisher":{"@id":"https:\/\/pre.efe.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#primaryimage"},"thumbnailUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg","articleSection":["Esportes","Portada"],"inLanguage":"pt-BR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/pre.efe.com\/#organization"}},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/","url":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/","name":"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso - EFE","isPartOf":{"@id":"https:\/\/pre.efe.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#primaryimage"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#primaryimage"},"thumbnailUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg","datePublished":"2023-09-15T19:21:00+00:00","dateModified":"2023-09-18T17:27:39+00:00","breadcrumb":{"@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#primaryimage","url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg","contentUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg","width":1920,"height":1282,"caption":"El expresidente de la Federaci\u00f3n Espa\u00f1ola de F\u00fatbol, Luis Rubiales en una foto de archivo. EFE\/JJ Guill\u00e9n"},{"@type":"BreadcrumbList","@id":"https:\/\/pre.efe.com\/pt-br\/esportes\/2023-09-15\/promotoria-solicita-que-rubiales-nao-se-aproxime-e-nem-tenha-contato-com-jenni-hermoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pre.efe.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Promotoria solicita que Rubiales n\u00e3o se aproxime e nem tenha contato com Jenni Hermoso"}]},{"@type":"WebSite","@id":"https:\/\/pre.efe.com\/pt-br\/#website","url":"https:\/\/pre.efe.com\/pt-br\/","name":"EFE Noticias","description":"","publisher":{"@id":"https:\/\/pre.efe.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pre.efe.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/pre.efe.com\/pt-br\/#organization","name":"Agencia EFE","url":"https:\/\/pre.efe.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/06\/logo-efe-467.png","contentUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/06\/logo-efe-467.png","width":467,"height":467,"caption":"Agencia EFE"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AgenciaEFEnoticias\/","https:\/\/x.com\/efenoticias","https:\/\/www.instagram.com\/efe_noticias\/","http:\/\/www.youtube.com\/efe"]},{"@type":"Person","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/person\/b19f23f210db552768f68a4b552b004f","name":"anachain","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","caption":"anachain"},"url":"https:\/\/pre.efe.com\/pt-br\/autor\/anachain\/"}]}},"jetpack_featured_media_url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/09\/rss-efe37d2ec56a62ae6c1aaa0a82c56cb25e8b136a8d1w.jpg","jetpack_shortlink":"https:\/\/wp.me\/peJvHm-2JfX","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/650625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/users\/198164106"}],"replies":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/comments?post=650625"}],"version-history":[{"count":2,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/650625\/revisions"}],"predecessor-version":[{"id":650633,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/650625\/revisions\/650633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/media\/637785"}],"wp:attachment":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/media?parent=650625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/categories?post=650625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/tags?post=650625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}