{"id":967795,"date":"2024-03-11T16:17:00","date_gmt":"2024-03-11T15:17:00","guid":{"rendered":"https:\/\/pre.efe.com\/?p=967795"},"modified":"2024-03-11T18:21:23","modified_gmt":"2024-03-11T17:21:23","slug":"apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan","status":"publish","type":"post","link":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/","title":{"rendered":"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN"},"content":{"rendered":"\n<p>Bruxelas (EFE).- A bandeira da Su\u00e9cia foi hasteada nesta segunda-feira no quartel-general da OTAN em Bruxelas, assim como em suas sedes na Europa e na Am\u00e9rica do Norte, em uma cerim\u00f4nia para celebrar a entrada oficial do pa\u00eds n\u00f3rdico na Alian\u00e7a Atl\u00e2ntica, na qual n\u00e3o faltaram refer\u00eancias \u00e0 guerra na Ucr\u00e2nia.<\/p>\n\n\n\n<p>A bandeira foi hasteada no c\u00edrculo onde est\u00e3o os estandartes dos outros 31 aliados &#8211; entre as da Espanha e a da Turquia -, em frente \u00e0 sede principal da organiza\u00e7\u00e3o, em uma cerim\u00f4nia que aconteceu debaixo de chuva e na presen\u00e7a do secret\u00e1rio-geral da OTAN, Jens Stoltenberg, do primeiro-ministro sueco, Ulf Kristersson, e da princesa herdeira Vit\u00f3ria da Su\u00e9cia, bem como dos embaixadores dos pa\u00edses-membros.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;A ades\u00e3o da Su\u00e9cia demonstra mais uma vez que a porta da OTAN permanece aberta. Ningu\u00e9m pode fech\u00e1-la. Cada na\u00e7\u00e3o tem o direito de escolher seu pr\u00f3prio caminho. E todos n\u00f3s escolhemos o caminho da liberdade e da democracia. O corajoso povo da Ucr\u00e2nia est\u00e1 lutando por estes valores enquanto falamos&#8221;, disse Stoltenberg durante a cerim\u00f4nia.<\/p>\n<\/blockquote>\n\n\n\n<p>O pol\u00edtico noruegu\u00eas afirmou que, durante os 75 anos de hist\u00f3ria da Alian\u00e7a, \u201ca liga\u00e7\u00e3o transatl\u00e2ntica entre a Europa e a Am\u00e9rica do Norte garantiu nossa liberdade e seguran\u00e7a\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-paz-e-seguranca\">Paz e seguran\u00e7a<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Como amigo e vizinho n\u00f3rdico, estou muito orgulhoso de que a Su\u00e9cia agora se junte a n\u00f3s nesta miss\u00e3o essencial. Hoje, ao hastear a bandeira sueca, estamos unidos e solid\u00e1rios. Comprometidos em proteger e defender uns aos outros. Todos por um e um por todos&#8221;, enfatizou.<\/p>\n<\/blockquote>\n\n\n\n<p>Por sua vez, Kristersson disse que a Su\u00e9cia, que na semana passada completou os procedimentos legais necess\u00e1rios para a ades\u00e3o em Washington, \u201c\u00e9 um orgulhoso membro da OTAN, a organiza\u00e7\u00e3o para paz e seguran\u00e7a mais bem sucedida que j\u00e1 existiu\u201d.<\/p>\n\n\n\n<p>\u201cAgora somos um aliado entre aliados depois de mais de 200 anos de n\u00e3o-alinhamento militar. \u00c9 um passo hist\u00f3rico, mas tamb\u00e9m muito natural\u201d, acrescentou.<\/p>\n\n\n\n<p>O chefe de governo sueco comentou ainda que se preparavam para isso h\u00e1 d\u00e9cadas e mais intensamente nos \u00faltimos dois anos, ap\u00f3s a invas\u00e3o russa da Ucr\u00e2nia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cCom esta ades\u00e3o, a Su\u00e9cia regressou para casa, o lar da coopera\u00e7\u00e3o em mat\u00e9ria de seguran\u00e7a das democracias, o lar da coopera\u00e7\u00e3o em mat\u00e9ria de seguran\u00e7a dos nossos bons vizinhos\u201d, completou.<\/p>\n<\/blockquote>\n\n\n\n<p>A Su\u00e9cia candidatou-se \u00e0 ades\u00e3o \u00e0 OTAN em maio de 2022, juntamente com a Finl\u00e2ndia, que se tornou membro de pleno direito no ano passado, mas a relut\u00e2ncia de dois dos membros da organiza\u00e7\u00e3o, a Turquia e a Hungria, atrasou a entrada durante quase dois anos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mudanca-de-geografia\">Mudan\u00e7a de geografia<\/h2>\n\n\n\n<p>Em um pronunciamento \u00e0 imprensa ao lado do l\u00edder sueco antes da cerim\u00f3nia, Stoltenberg garantiu que com a entrada da Su\u00e9cia \u201ca geografia muda\u201d, porque deixaram de estar focados nas vulnerabilidades da regi\u00e3o b\u00e1ltica para terem \u201cdois aliados importantes tamb\u00e9m no lado ocidental do Mar B\u00e1ltico&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cA Su\u00e9cia est\u00e1 mais segura dentro da OTAN do que fora dela e a OTAN \u00e9 mais forte com a Su\u00e9cia\u201d, resumiu Stoltenberg, elogiando o pa\u00eds n\u00f3rdico por suas capacidades de ponta, uma forte ind\u00fastria militar e por gastar mais de 2% de seu Produto Interno Bruto (PIB) na \u00e1rea de Defesa.<\/p>\n<\/blockquote>\n\n\n\n<p>J\u00e1 Kristersson sustentou que \u201ca situa\u00e7\u00e3o de seguran\u00e7a na nossa regi\u00e3o n\u00e3o havia sido t\u00e3o grave desde a Segunda Guerra Mundial\u201d e previu que a R\u00fassia \u201ccontinuar\u00e1 a ser uma amea\u00e7a \u00e0 seguran\u00e7a euro-atl\u00e2ntica no futuro\u201d.<\/p>\n\n\n\n<p>\u201cPerante isto, a Su\u00e9cia solicitou a ades\u00e3o \u00e0 alian\u00e7a de defesa da OTAN n\u00e3o s\u00f3 para obter seguran\u00e7a, mas tamb\u00e9m para fornec\u00ea-la\u201d, destacou.<\/p>\n\n\n\n<p>Em qualquer caso, Stoltenberg indicou que a OTAN n\u00e3o tem planos de expandir o n\u00famero de aliados que possuem armas nucleares ou de mobilizar um batalh\u00e3o na Su\u00e9cia como os que mant\u00e9m nos pa\u00edses b\u00e1lticos.<\/p>\n\n\n\n<p>Nesse sentido, Kristersson disse compreender perfeitamente a necessidade de todas as capacidades de defesa da OTAN, incluindo a estrat\u00e9gia nuclear, mas que n\u00e3o v\u00ea necessidade de a Su\u00e9cia acolher uma base permanente ou armas nucleares no seu territ\u00f3rio em tempos de paz. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruxelas (EFE).- A bandeira da Su\u00e9cia foi hasteada nesta segunda-feira no quartel-general da OTAN em Bruxelas, assim como em suas sedes na Europa e na Am\u00e9rica do Norte, em uma cerim\u00f4nia para celebrar a entrada oficial do pa\u00eds n\u00f3rdico na Alian\u00e7a Atl\u00e2ntica, na qual n\u00e3o faltaram refer\u00eancias \u00e0 guerra na Ucr\u00e2nia. A bandeira foi hasteada &#8230; <a title=\"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN\" class=\"read-more\" href=\"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/\" aria-label=\"Read more about Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN\">Leia mais<\/a><\/p>\n","protected":false},"author":198164106,"featured_media":966741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[123208,122141],"tags":[122791,122957,122958],"class_list":["post-967795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-2","category-portada","tag-guerra-2","tag-otan","tag-russia-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN - EFE<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN - EFE\" \/>\n<meta property=\"og:description\" content=\"Bruxelas (EFE).- A bandeira da Su\u00e9cia foi hasteada nesta segunda-feira no quartel-general da OTAN em Bruxelas, assim como em suas sedes na Europa e na Am\u00e9rica do Norte, em uma cerim\u00f4nia para celebrar a entrada oficial do pa\u00eds n\u00f3rdico na Alian\u00e7a Atl\u00e2ntica, na qual n\u00e3o faltaram refer\u00eancias \u00e0 guerra na Ucr\u00e2nia. A bandeira foi hasteada ... Leia mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/\" \/>\n<meta property=\"og:site_name\" content=\"EFE Noticias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AgenciaEFEnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-11T15:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T17:21:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/efe.com\/\/srv\/htdocs\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg?fit=900%2C708&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anachain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@efenoticias\" \/>\n<meta name=\"twitter:site\" content=\"@efenoticias\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/\"},\"author\":{\"name\":\"anachain\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b19f23f210db552768f68a4b552b004f\"},\"headline\":\"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN\",\"datePublished\":\"2024-03-11T15:17:00+00:00\",\"dateModified\":\"2024-03-11T17:21:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/\"},\"wordCount\":763,\"publisher\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BANDERA-SUECIA-OTAN.jpg\",\"keywords\":[\"Guerra\",\"OTAN\",\"Russia\"],\"articleSection\":[\"Mundo\",\"Portada\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/#organization\"}},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/\",\"name\":\"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN - EFE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BANDERA-SUECIA-OTAN.jpg\",\"datePublished\":\"2024-03-11T15:17:00+00:00\",\"dateModified\":\"2024-03-11T17:21:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BANDERA-SUECIA-OTAN.jpg\",\"contentUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/BANDERA-SUECIA-OTAN.jpg\",\"width\":900,\"height\":708,\"caption\":\"EFE\\\/EPA\\\/OLIVIER MATTHYS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/mundo-2\\\/2024-03-11\\\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\",\"name\":\"EFE Noticias\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#organization\",\"name\":\"Agencia EFE\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-efe-467.png\",\"contentUrl\":\"https:\\\/\\\/pre.efe.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-efe-467.png\",\"width\":467,\"height\":467,\"caption\":\"Agencia EFE\"},\"image\":{\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AgenciaEFEnoticias\\\/\",\"https:\\\/\\\/x.com\\\/efenoticias\",\"https:\\\/\\\/www.instagram.com\\\/efe_noticias\\\/\",\"http:\\\/\\\/www.youtube.com\\\/efe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b19f23f210db552768f68a4b552b004f\",\"name\":\"anachain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g\",\"caption\":\"anachain\"},\"url\":\"https:\\\/\\\/pre.efe.com\\\/pt-br\\\/autor\\\/anachain\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN - EFE","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_BR","og_type":"article","og_title":"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN - EFE","og_description":"Bruxelas (EFE).- A bandeira da Su\u00e9cia foi hasteada nesta segunda-feira no quartel-general da OTAN em Bruxelas, assim como em suas sedes na Europa e na Am\u00e9rica do Norte, em uma cerim\u00f4nia para celebrar a entrada oficial do pa\u00eds n\u00f3rdico na Alian\u00e7a Atl\u00e2ntica, na qual n\u00e3o faltaram refer\u00eancias \u00e0 guerra na Ucr\u00e2nia. A bandeira foi hasteada ... Leia mais","og_url":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/","og_site_name":"EFE Noticias","article_publisher":"https:\/\/www.facebook.com\/AgenciaEFEnoticias\/","article_published_time":"2024-03-11T15:17:00+00:00","article_modified_time":"2024-03-11T17:21:23+00:00","og_image":[{"width":900,"height":708,"url":"https:\/\/i0.wp.com\/efe.com\/\/srv\/htdocs\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg?fit=900%2C708&ssl=1","type":"image\/jpeg"}],"author":"anachain","twitter_card":"summary_large_image","twitter_creator":"@efenoticias","twitter_site":"@efenoticias","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#article","isPartOf":{"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/"},"author":{"name":"anachain","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/person\/b19f23f210db552768f68a4b552b004f"},"headline":"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN","datePublished":"2024-03-11T15:17:00+00:00","dateModified":"2024-03-11T17:21:23+00:00","mainEntityOfPage":{"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/"},"wordCount":763,"publisher":{"@id":"https:\/\/pre.efe.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#primaryimage"},"thumbnailUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg","keywords":["Guerra","OTAN","Russia"],"articleSection":["Mundo","Portada"],"inLanguage":"pt-BR","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/pre.efe.com\/#organization"}},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/","url":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/","name":"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN - EFE","isPartOf":{"@id":"https:\/\/pre.efe.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#primaryimage"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#primaryimage"},"thumbnailUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg","datePublished":"2024-03-11T15:17:00+00:00","dateModified":"2024-03-11T17:21:23+00:00","breadcrumb":{"@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#primaryimage","url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg","contentUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg","width":900,"height":708,"caption":"EFE\/EPA\/OLIVIER MATTHYS"},{"@type":"BreadcrumbList","@id":"https:\/\/pre.efe.com\/pt-br\/mundo-2\/2024-03-11\/apos-adesao-bandeira-da-suecia-e-hasteada-nas-sedes-da-otan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pre.efe.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Ap\u00f3s ades\u00e3o, bandeira da Su\u00e9cia \u00e9 hasteada nas sedes da OTAN"}]},{"@type":"WebSite","@id":"https:\/\/pre.efe.com\/pt-br\/#website","url":"https:\/\/pre.efe.com\/pt-br\/","name":"EFE Noticias","description":"","publisher":{"@id":"https:\/\/pre.efe.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pre.efe.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/pre.efe.com\/pt-br\/#organization","name":"Agencia EFE","url":"https:\/\/pre.efe.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/06\/logo-efe-467.png","contentUrl":"https:\/\/pre.efe.com\/wp-content\/uploads\/2023\/06\/logo-efe-467.png","width":467,"height":467,"caption":"Agencia EFE"},"image":{"@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AgenciaEFEnoticias\/","https:\/\/x.com\/efenoticias","https:\/\/www.instagram.com\/efe_noticias\/","http:\/\/www.youtube.com\/efe"]},{"@type":"Person","@id":"https:\/\/pre.efe.com\/pt-br\/#\/schema\/person\/b19f23f210db552768f68a4b552b004f","name":"anachain","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30b83965911ef1108bb893c00bdd65c885f9890e1265ee04b02c3d5adc785d37?s=96&d=identicon&r=g","caption":"anachain"},"url":"https:\/\/pre.efe.com\/pt-br\/autor\/anachain\/"}]}},"jetpack_featured_media_url":"https:\/\/pre.efe.com\/wp-content\/uploads\/2024\/03\/BANDERA-SUECIA-OTAN.jpg","jetpack_shortlink":"https:\/\/wp.me\/peJvHm-43LB","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/967795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/users\/198164106"}],"replies":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/comments?post=967795"}],"version-history":[{"count":3,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/967795\/revisions"}],"predecessor-version":[{"id":967821,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/posts\/967795\/revisions\/967821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/media\/966741"}],"wp:attachment":[{"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/media?parent=967795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/categories?post=967795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pre.efe.com\/pt-br\/wp-json\/wp\/v2\/tags?post=967795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}